{"id":49893,"date":"2025-12-31T20:56:20","date_gmt":"2025-12-31T18:56:20","guid":{"rendered":"https:\/\/www.animille.com\/produkt\/skora-wieprzowa-platy-200g\/"},"modified":"2026-08-17T17:25:09","modified_gmt":"2026-08-17T16:25:09","slug":"skora-wieprzowa-platy-200g","status":"publish","type":"product","link":"https:\/\/www.animille.com\/it\/prodotto\/skora-wieprzowa-platy-200g\/","title":{"rendered":"Sk\u00f3ra Wieprzowa P\u0142aty 200g"},"content":{"rendered":"<p>I masticatori di pelle di maiale sono tra i pi\u00f9 resistenti per i cani. Sono ricchi di prolina, un aminoacido essenziale per il ripristino del collagene. Sia i cuccioli che i cani adulti possono mangiarli senza problemi. Inoltre, supporta i cani giovani durante il periodo di sostituzione dei denti.<\/p>","protected":false},"excerpt":{"rendered":"<p>I masticatori di pelle di maiale sono tra i pi\u00f9 resistenti per i cani. Sono ricchi di prolina, un aminoacido essenziale per il ripristino del collagene. Sia i cuccioli che i cani adulti possono mangiarli senza problemi. Inoltre, supporta i cani giovani durante il periodo di sostituzione dei denti.<\/p>","protected":false},"featured_media":49885,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[1242,1247],"product_tag":[],"class_list":{"0":"post-49893","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-wieprzowina","7":"product_cat-wieprzowina-koty","9":"first","10":"instock","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/www.animille.com\/it\/wp-json\/wp\/v2\/product\/49893","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.animille.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.animille.com\/it\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.animille.com\/it\/wp-json\/wp\/v2\/comments?post=49893"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.animille.com\/it\/wp-json\/wp\/v2\/media\/49885"}],"wp:attachment":[{"href":"https:\/\/www.animille.com\/it\/wp-json\/wp\/v2\/media?parent=49893"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.animille.com\/it\/wp-json\/wp\/v2\/product_brand?post=49893"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.animille.com\/it\/wp-json\/wp\/v2\/product_cat?post=49893"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.animille.com\/it\/wp-json\/wp\/v2\/product_tag?post=49893"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}